{"id":1301,"date":"2026-02-10T06:46:00","date_gmt":"2026-02-10T05:46:00","guid":{"rendered":"https:\/\/nicotondeur.fr\/?p=1301"},"modified":"2026-02-11T14:22:10","modified_gmt":"2026-02-11T13:22:10","slug":"pourquoi-techsys","status":"publish","type":"post","link":"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/","title":{"rendered":"Pourquoi Techsys?"},"content":{"rendered":"\n<p>Fin 2025, j\u2019ai pris du temps, presque 3 mois, sans aucun engagement professionnel. Certes, comme dirait ma compagne, je ne me suis pas du tout repos\u00e9 durant cette p\u00e9riode, mais j\u2019avais besoin de temps pour me recentrer.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"482\" data-attachment-id=\"1302\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/15299-darts-102919_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?fit=1280%2C853&amp;ssl=1\" data-orig-size=\"1280,853\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"15299-darts-102919_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?fit=723%2C482&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?resize=723%2C482&#038;ssl=1\" alt=\"Cible avec fl\u00e9chettes\" class=\"wp-image-1302\" style=\"aspect-ratio:1.5015018813039491;width:322px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/15299-darts-102919_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image de Pixabay<\/figcaption><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\">\n<li>Me recentrer sur mes envies et capacit\u00e9s entant qu\u2019accompagnateur des organisations.<\/li>\n\n\n\n<li>Me recentrer sur mes besoins entant que travailleur (salari\u00e9 ou pas).<\/li>\n\n\n\n<li>Me recentrer sur ce que je suis (qui je suis) entant qu\u2019humain.<\/li>\n<\/ul>\n\n\n\n<p>Comme le dit si bien <a href=\"https:\/\/www.linkedin.com\/in\/bcabanne\/\">Benjamin Cabanne<\/a>, il a fallu qu\u2019avant tout je me recentre sur le fait que \u201c<a href=\"https:\/\/youtu.be\/idrsM3sOZew?si=kqW1HaJO7rpKYLiq\">je suis juste humain<\/a>\u201d.<\/p>\n\n\n\n<p>Mais ce cheminement ne pouvait pas se faire tout seul. Alors j\u2019ai appel\u00e9 \u00e0 l\u2019aide. D\u2019abord, pour m\u2019exprimer et confronter ma situation \u00e0 ce que d\u2019autres ont v\u00e9cus, j\u2019ai parl\u00e9 \u00e0 beaucoup de copains du m\u00e9tier et des r\u00e9seaux (merci \u00e0 <a href=\"https:\/\/www.linkedin.com\/in\/duboisrachel\/\">Rachel<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/stephane-delbecque\/\">St\u00e9phane<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/sebastien-noule\/\">S\u00e9bastien<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/aurelienmorvant\/\">Aur\u00e9lien<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/sophiepruvost\/\">Sophie<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/romain-rozewicz\/\">Romain<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/marion-chupin-aa7987aa\/\">Marion<\/a>, <a href=\"https:\/\/www.linkedin.com\/in\/antoine-blois\/\">Antoine<\/a>\u2026 et j\u2019en oublie sans doute).<\/p>\n\n\n\n<p>Puis j\u2019ai d\u00e9cid\u00e9, sur les conseils de <a href=\"https:\/\/www.linkedin.com\/in\/duboisrachel\/\">Rachel<\/a>, de me lancer dans un Ikigai (tient, comme c\u2019est original pour un agiliste de la premi\u00e8re heure).<\/p>\n\n\n\n<p>Suite \u00e0 un travail d\u2019introspection avec <a href=\"https:\/\/www.linkedin.com\/in\/sebastien-noule\/\">S\u00e9bastien<\/a>, j\u2019ai fini par r\u00e9ussir \u00e0 me d\u00e9finir entant qu\u2019individu : \u201cJe suis joueur\u201d<\/p>\n\n\n\n<p>A partir de ce constat, et de cette acceptation, il ne me restait plus qu\u2019\u00e0 d\u00e9cider ce que j\u2019allais faire par la suite.<\/p>\n\n\n\n<p>La voie de l\u2019ind\u00e9pendance \u00e9tait devant moi, mais \u00e0 l\u2019intersection se trouvait aussi la possibilit\u00e9 de reprendre une activit\u00e9 salari\u00e9e.<\/p>\n\n\n\n<p>En effet, lorsque j\u2019ai annonc\u00e9 \u00e0 certaines connaissances ma disponibilit\u00e9, j\u2019ai eu le plaisir de les voir montrer de l\u2019int\u00e9r\u00eat \u00e0 une collaboration.<\/p>\n\n\n\n<p>Comme vous l\u2019avez remarqu\u00e9, j\u2019ai accept\u00e9 la proposition de Techsys (enfin de <a href=\"https:\/\/www.linkedin.com\/in\/sophiepruvost\/\">Sophie<\/a> et <a href=\"https:\/\/www.linkedin.com\/in\/gmaerte\/\">Guillaume<\/a>), et je vais d\u00e9tailler un peu le pourquoi\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Nico est un animal social.<\/strong><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"849\" data-attachment-id=\"1303\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/alexas_fotos-penguin-4893026_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?fit=1090%2C1280&amp;ssl=1\" data-orig-size=\"1090,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"alexas_fotos-penguin-4893026_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?fit=723%2C849&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?resize=723%2C849&#038;ssl=1\" alt=\"Un pingu\u00efn tout seul\" class=\"wp-image-1303\" style=\"aspect-ratio:0.8515735676499596;width:225px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?resize=872%2C1024&amp;ssl=1 872w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?resize=255%2C300&amp;ssl=1 255w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?resize=768%2C902&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-penguin-4893026_1280.jpg?w=1090&amp;ssl=1 1090w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image by&nbsp;<a href=\"https:\/\/pixabay.com\/users\/alexas_fotos-686414\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=4893026\">Alexa<\/a>&nbsp;from&nbsp;<a href=\"https:\/\/pixabay.com\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=4893026\">Pixabay<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Entant que joueur, je n\u2019aime pas particuli\u00e8rement jouer seul\u2026 M\u2019imaginer \u00e0 la maison, seul,  lorsque je ne suis pas avec un client, est tr\u00e8s difficile.<\/p>\n\n\n\n<p>Il me faut donc avoir un environnement d\u2019\u00e9change disponible. J\u2019aurais pu envisager de prendre un bureau dans un espace partag\u00e9, mais j\u2019avoue que mes exp\u00e9riences de production \u00e0 plusieurs ind\u00e9pendants m\u2019ont appris que synchroniser des agendas est difficile lorsque nous ne faisons pas tous parti de la m\u00eame soci\u00e9t\u00e9. Or, comme j\u2019ai aussi besoin d\u2019aboutir \u00e0 des conclusions \/ productions, si je ne peux avoir acc\u00e8s aux personnes avec qui j\u2019ai commenc\u00e9 une collaboration, j\u2019ajoute \u00e0 ma charge mentale\u2026<\/p>\n\n\n\n<p>Ca ne veut pas dire que je ne veux pas collaborer en ext\u00e9rieur, loin de l\u00e0, mais \u00e7a implique que je dois aussi me mettre en capacit\u00e9 de produire des choses avec des coll\u00e8gues r\u00e9guli\u00e8rement, sans toujours remettre aux calendes grecques.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Nico est fait pour construire et exp\u00e9rimenter en interne.<\/strong><\/h3>\n\n\n\n<p>J\u2019ai donc besoin de produire des contenus, des serious games\u2026 mais pas juste pour le fait de produire\u2026 j\u2019ai aussi besoin d\u2019avoir un but sur le long terme.<\/p>\n\n\n\n<p>Produire pour un client, lorsqu\u2019un besoin pr\u00e9cis est identifi\u00e9, est absolument g\u00e9nial et indispensable, cependant, j\u2019ai aussi besoin de participer \u00e0 un collectif sur le long terme.<\/p>\n\n\n\n<p>Certes, j\u2019ai la chance d\u2019\u00eatre actif dans plusieurs communaut\u00e9s actuellement (<a href=\"https:\/\/nord-agile.org\">Nord Agile<\/a>, <a href=\"https:\/\/www.sgd-syndicat.org\">le Syndicat des Serious Games Designers<\/a>, <a href=\"https:\/\/keikenchiba.org\">Keikenchiba<\/a>\u2026), cependant elles restent des communaut\u00e9s, des groupes qui sont form\u00e9s autour d\u2019un int\u00e9r\u00eat commun, cibl\u00e9, et donc avec des travaux tr\u00e8s orient\u00e9s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"516\" data-attachment-id=\"1304\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/oslometx-experiment-4415977_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?fit=1280%2C914&amp;ssl=1\" data-orig-size=\"1280,914\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"oslometx-experiment-4415977_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?fit=723%2C516&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?resize=723%2C516&#038;ssl=1\" alt=\"Tubes \u00e0 essai et b\u00e9cher de laboratoire\" class=\"wp-image-1304\" style=\"aspect-ratio:1.4008259587020648;width:301px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?resize=1024%2C731&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?resize=300%2C214&amp;ssl=1 300w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?resize=768%2C548&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/oslometx-experiment-4415977_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image by&nbsp;<a href=\"https:\/\/pixabay.com\/users\/oslometx-7322944\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=4415977\">OsloMetX<\/a>&nbsp;from&nbsp;<a href=\"https:\/\/pixabay.com\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=4415977\">Pixabay<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p>J\u2019ai besoin de produire avec un groupe dans une optique d\u2019am\u00e9lioration plus g\u00e9n\u00e9rale (am\u00e9lioration de l\u2019organisation, am\u00e9lioration des relations, am\u00e9lioration du vivant\u2026).<\/p>\n\n\n\n<p>De plus, la richesse, je pense, de mes interventions aupr\u00e8s des clients, vient en grande partie de mon exp\u00e9rience, du fait que ce que je propose aux clients ou que les interrogations qu\u2019ils se posent, se soient d\u00e9j\u00e0 manifest\u00e9es \u00e0 ou devant moi\u2026<\/p>\n\n\n\n<p>En dehors d\u2019une structure, rester coh\u00e9rent dans ces exp\u00e9riences pour les clients m\u2019aurait demand\u00e9 d\u2019avantage d\u2019efforts.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Techsys est en pleine \u00e9volution<\/h3>\n\n\n\n<p>Depuis que je connais <a href=\"https:\/\/techsys.fr\">Techsys<\/a> j\u2019ai eu la chance de voir leur fonctionnement collaboratif et le virage \u00e9co-social qu\u2019ils ont pris.<\/p>\n\n\n\n<p>D\u2019ESN assez traditionnelle, ils sont pass\u00e9s au fur et \u00e0 mesure des ann\u00e9es, \u00e0 un mod\u00e8le d\u2019<a href=\"https:\/\/techsys.fr\/les-assos\/\">associ\u00e9s salari\u00e9s<\/a> assurants la gouvernance puis \u00e0 une entreprise soucieuse de son impact \u00e9co-social, en passant par la mise en place d\u2019actions collaboratives internes, externes ainsi qu\u2019en suivant le <a href=\"https:\/\/techsys.fr\/cec\/\">parcours CEC<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"333\" data-attachment-id=\"1305\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/kellepics-evolution-7074064_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?fit=1280%2C590&amp;ssl=1\" data-orig-size=\"1280,590\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"kellepics-evolution-7074064_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?fit=723%2C333&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?resize=723%2C333&#038;ssl=1\" alt=\"L'\u00e9volution illustr\u00e9e du singe \u00e0 l'homme puis retour au singe\" class=\"wp-image-1305\" style=\"width:272px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?resize=1024%2C472&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?resize=300%2C138&amp;ssl=1 300w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?resize=768%2C354&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/kellepics-evolution-7074064_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image by&nbsp;<a href=\"https:\/\/pixabay.com\/users\/kellepics-4893063\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=7074064\">Stefan Keller<\/a>&nbsp;from&nbsp;<a href=\"https:\/\/pixabay.com\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=7074064\">Pixabay<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p>La suite de l\u2019aventure Techsys passe par la certification B-Corp et plus encore.<\/p>\n\n\n\n<p>Si vous me connaissez un petit peu, vous vous doutez bien que toute cette \u00e9volution sonne tendrement \u00e0 mon oreille \ud83d\ude09<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cr\u00e9er de la valeur en interne et en externe<\/h3>\n\n\n\n<p>Pour continuer \u00e0 \u00e9voluer, le mode de fonctionnement interne se doit de s\u2019adapter, et c\u2019est pour cela que notre collaboration pour l\u2019interne faisait sens : amener un regard nouveau, externe (au moins au d\u00e9but) et curieux sur le fonctionnement de <a href=\"https:\/\/techsys.fr\/\">Techsys<\/a> et notamment sur celui de la direction.<\/p>\n\n\n\n<p>C\u2019est en cela que mon r\u00f4le interne prend son importance. Je vais donc coordonner l\u2019animation du collaboratif en interne, accompagner la direction et tout <a href=\"https:\/\/techsys.fr\/\">Techsys<\/a> dans les \u00e9volutions n\u00e9cessaires \u00e0 tenir leurs ambitions, tout en apprenant beaucoup sur le chemin, afin de nourrir mes capacit\u00e9s d\u2019accompagnement des clients.<\/p>\n\n\n\n<p>Etant le seul sp\u00e9cialis\u00e9 dans l\u2019accompagnement d\u2019organisations, je vais \u00e9galement pouvoir cr\u00e9er ma propre \u201coffre\u201d autour de mes savoirs faire, tout en faisant sens au sein de l\u2019\u00e9cosyst\u00e8me <a href=\"https:\/\/techsys.fr\/\">Techsys<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"482\" data-attachment-id=\"1306\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/geralt-hierarchy-2499789_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?fit=1280%2C854&amp;ssl=1\" data-orig-size=\"1280,854\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"geralt-hierarchy-2499789_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?fit=723%2C482&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?resize=723%2C482&#038;ssl=1\" alt=\"Diagramme d'organisation avec des silhouettes humaines\" class=\"wp-image-1306\" style=\"aspect-ratio:1.499291042475803;width:305px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/geralt-hierarchy-2499789_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image by&nbsp;<a href=\"https:\/\/pixabay.com\/users\/geralt-9301\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=2499789\">Gerd Altmann<\/a>&nbsp;from&nbsp;<a href=\"https:\/\/pixabay.com\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=2499789\">Pixabay<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Comment me direz-vous? <a href=\"https:\/\/www.linkedin.com\/in\/sophiepruvost\/\">Sophie<\/a> le pose elle m\u00eame en ces mots : \u201cChez Techsys nous sommes des pros de l\u2019OPS, des passionn\u00e9s de l\u2019architecture des syst\u00e8mes et de leur optimisation. Quand on sait, notamment via la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Loi_de_Conway\">loi de Conway<\/a>, que l\u2019architecture des syst\u00e8mes est le reflet de l\u2019organisation de l\u2019entreprise, il fait sens, quand on veut \u00eatre les acteurs de l\u2019optimisation des SI, qu\u2019on regarde \u00e9galement au fonctionnement des humains utilisant \/ produisant le syst\u00e8me d\u2019information\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Une relation humaine par dessus tout<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.linkedin.com\/in\/sophiepruvost\/\">Sophie<\/a> et <a href=\"https:\/\/www.linkedin.com\/in\/gmaerte\/\">Guillaume<\/a> ont pris un engagement fort en m\u2019int\u00e9grant \u00e0 l\u2019entreprise. C\u2019est un pari sur notre capacit\u00e9 collective \u00e0 faire \u00e9voluer <a href=\"https:\/\/techsys.fr\/\">Techsys<\/a> au del\u00e0 de ses limitations actuelles, dans le respect de leur vision \u00e9co-sociale, tout en misant sur le fait que les partenariats que nous monterons sur le chemin apporteront suffisamment de challenges pour nourrir un app\u00e9tit comme le mien.<\/p>\n\n\n\n<p>Mais c\u2019est aussi, et avant tout, la volont\u00e9 partag\u00e9e de continuer une aventure humaine commenc\u00e9e au sortir du confinement par le financement participatif de <a href=\"https:\/\/nicotondeur.fr\/index.php\/2019\/06\/21\/stressss\/\" data-type=\"post\" data-id=\"145\">Stressss!!! V2.0<\/a>.<\/p>\n\n\n\n<p>Des humains, qui ont rencontr\u00e9s un humain en se disant : \u00e7a serait bien qu\u2019on collabore !<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"723\" height=\"332\" data-attachment-id=\"1307\" data-permalink=\"https:\/\/nicotondeur.fr\/index.php\/2026\/02\/10\/pourquoi-techsys\/alexas_fotos-humanity-2045992_1280\/\" data-orig-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?fit=1280%2C587&amp;ssl=1\" data-orig-size=\"1280,587\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"alexas_fotos-humanity-2045992_1280\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?fit=723%2C332&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?resize=723%2C332&#038;ssl=1\" alt=\"Humanity \u00e9pel\u00e9 avec des lettres de Scrabble\" class=\"wp-image-1307\" style=\"aspect-ratio:2.178748394200771;width:357px;height:auto\" srcset=\"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?resize=1024%2C470&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?resize=300%2C138&amp;ssl=1 300w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?resize=768%2C352&amp;ssl=1 768w, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 723px) 100vw, 723px\" \/><figcaption class=\"wp-element-caption\">Image by&nbsp;<a href=\"https:\/\/pixabay.com\/users\/alexas_fotos-686414\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=2045992\">Alexa<\/a>&nbsp;from&nbsp;<a href=\"https:\/\/pixabay.com\/\/?utm_source=link-attribution&amp;utm_medium=referral&amp;utm_campaign=image&amp;utm_content=2045992\">Pixabay<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Nous poussons maintenant la collaboration au niveau sup\u00e9rieur, et je dois dire que je suis d\u00e9j\u00e0, apr\u00e8s seulement un mois, enchant\u00e9 de cette \u00e9volution et surtout reconnaissant envers <a href=\"https:\/\/www.linkedin.com\/in\/sophiepruvost\/\">Sophie<\/a> et <a href=\"https:\/\/www.linkedin.com\/in\/gmaerte\/\">Guillaume<\/a> de m\u2019avoir montr\u00e9 leur c\u00f4t\u00e9 humain dans la relation direction \/ salari\u00e9.<\/p>\n\n\n\n<p>Je suis persuad\u00e9 que nous irons loin. Le chemin ne sera pas sans embuches, nous sommes tout de m\u00eame humains, mais il sera aussi plein d\u2019apprentissages et de fou-rires.<\/p>\n\n\n\n<p>Alors, pourquoi <a href=\"https:\/\/techsys.fr\/\">Techsys<\/a>? Tout simplement parce que c\u2019est, pour moi, le bon endroit, au bon moment!<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin 2025, j\u2019ai pris du temps, presque 3 mois, sans aucun engagement professionnel. Certes, comme dirait ma compagne, je ne me suis pas du tout repos\u00e9 durant cette p\u00e9riode, mais j\u2019avais besoin de temps pour me recentrer. Comme le dit si bien Benjamin Cabanne, il a fallu qu\u2019avant tout je me recentre sur le fait [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Fin 2025, j\u2019ai pris du temps, presque 3 mois, sans aucun engagement professionnel.\nD\u00e9but 2026 j'ai repris avec Techsys. Alors que plusieurs choix se pr\u00e9sent\u00e9s \u00e0 moi, pourquoi est-ce que Techsys a retenu plus particuli\u00e8rement mon attention et en quoi je me retrouve dans cette nouvelle collaboration?","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[4,7,25],"class_list":{"0":"post-1301","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-non-classe","8":"tag-blog","9":"tag-coaching","10":"tag-decider-ensemble","12":"fallback-thumbnail"},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/02\/alexas_fotos-humanity-2045992_1280.jpg?fit=1280%2C587&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paJKjz-kZ","jetpack-related-posts":[{"id":539,"url":"https:\/\/nicotondeur.fr\/index.php\/2021\/01\/14\/buy-your-future\/","url_meta":{"origin":1301,"position":0},"title":"Buy your future","author":"Nico Tondeur","date":"14 janvier 2021","format":false,"excerpt":"Depuis quelques mois chez Nextoo, le GAG travaille \u00e0 l'atelier Buy Your Future qui permet de g\u00e9rer les entretiens annuels de mani\u00e8re plus ludique et interactive.","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2021\/01\/forward-1276288_1920.jpg?fit=1200%2C734&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2021\/01\/forward-1276288_1920.jpg?fit=1200%2C734&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2021\/01\/forward-1276288_1920.jpg?fit=1200%2C734&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2021\/01\/forward-1276288_1920.jpg?fit=1200%2C734&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2021\/01\/forward-1276288_1920.jpg?fit=1200%2C734&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1371,"url":"https:\/\/nicotondeur.fr\/index.php\/2026\/03\/17\/pourquoi-participer-a-un-evenement-serious-gaming\/","url_meta":{"origin":1301,"position":1},"title":"Pourquoi participer \u00e0 un \u00e9v\u00e9nement serious gaming ?","author":"Nico Tondeur","date":"17 mars 2026","format":false,"excerpt":"Table des ateliers disponibles Ce jeudi 12 mars 2026, j\u2019ai une fois de plus anim\u00e9 un meetup Serious Gaming organis\u00e9 par Nord Agile.Depuis quelques ann\u00e9es, j\u2019ai la chance de pouvoir profiter de ces moments communautaires. Entant que participant d\u2019abord, puis entant qu\u2019organisateur et animateur. Que fait-on dans ces \u00e9v\u00e9nements ?\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/03\/IMG_5626-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/03\/IMG_5626-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/03\/IMG_5626-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/03\/IMG_5626-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2026\/03\/IMG_5626-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":216,"url":"https:\/\/nicotondeur.fr\/index.php\/2019\/11\/08\/pourquoi-faire-ecrire-des-conferences-agiles\/","url_meta":{"origin":1301,"position":2},"title":"Pourquoi faire \/ \u00e9crire des conf\u00e9rences agiles?","author":"Nico Tondeur","date":"8 novembre 2019","format":false,"excerpt":"Ca fait maintenant quelques ann\u00e9es que je participe, au moins entant que spectateur, \u00e0 des conf\u00e9rences agiles (Agile Tour, Meetups...). Il m'a fallu un peu de courage pour cr\u00e9er ma premi\u00e8re conf\u00e9rence, et j'avoue que participer \u00e0 l'Agile Game France \u00e0 Lille en 2017 m'a vraiment d\u00e9bloqu\u00e9. En effet, c'est\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"Image parBonnie Taylor de Pixabay","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/11\/auditorium-572776_1920.jpg?fit=1200%2C473&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/11\/auditorium-572776_1920.jpg?fit=1200%2C473&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/11\/auditorium-572776_1920.jpg?fit=1200%2C473&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/11\/auditorium-572776_1920.jpg?fit=1200%2C473&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/11\/auditorium-572776_1920.jpg?fit=1200%2C473&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":806,"url":"https:\/\/nicotondeur.fr\/index.php\/2022\/08\/29\/spike-ou-poc\/","url_meta":{"origin":1301,"position":3},"title":"Spike ou POC?","author":"Nico Tondeur","date":"29 ao\u00fbt 2022","format":false,"excerpt":"Quand une \u00e9quipe explore de nouveaux sujets, elle doit souvent faire le choix entre la recherche d'exp\u00e9rience ou la validation de concept... Je vous propose d'explorer deux moyens mis \u00e0 leur disposition: Spike et POC","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/08\/test-214185_1280.jpg?fit=1200%2C794&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/08\/test-214185_1280.jpg?fit=1200%2C794&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/08\/test-214185_1280.jpg?fit=1200%2C794&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/08\/test-214185_1280.jpg?fit=1200%2C794&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/08\/test-214185_1280.jpg?fit=1200%2C794&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":141,"url":"https:\/\/nicotondeur.fr\/index.php\/2019\/07\/05\/la-solitude-du-coach\/","url_meta":{"origin":1301,"position":4},"title":"La solitude du coach","author":"Nico Tondeur","date":"5 juillet 2019","format":false,"excerpt":"\"Elle est belle la vie de coach, tu vois des personnes diff\u00e9rentes tout le temps\". \"Toi t'es coach, tu dois \u00eatre une \"people person\"\". Oui, c'est vrai qu'\u00eatre coach agile (ou agent du changement), c'est presque toujours travailler avec des groupes ou des individus, interagir, \u00e9changer, parler, mais j'avoue que\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"Image parJonny Lindner de Pixabay","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/05\/wolf-1341881_1920.jpg?fit=1200%2C633&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/05\/wolf-1341881_1920.jpg?fit=1200%2C633&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/05\/wolf-1341881_1920.jpg?fit=1200%2C633&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/05\/wolf-1341881_1920.jpg?fit=1200%2C633&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2019\/05\/wolf-1341881_1920.jpg?fit=1200%2C633&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":827,"url":"https:\/\/nicotondeur.fr\/index.php\/2022\/12\/06\/mon-agile-greenoble-2022\/","url_meta":{"origin":1301,"position":5},"title":"Mon Agile Greenoble 2022","author":"Nico Tondeur","date":"6 d\u00e9cembre 2022","format":false,"excerpt":"Les 23, 24 et 25 Novembre 2022 avait lieu Agile Greenoble 2022 (ce n\u2019est pas une faute de frappe). Cet \u00e9v\u00e9nement agile, teint\u00e9 cette ann\u00e9e sur l\u2019\u00e9co-responsabilit\u00e9, fait partie de mes incontournables chaque ann\u00e9e. Je vous propose d\u2019explorer avec moi plusieurs aspects autour de cet \u00e9v\u00e9nement\u00a0: La d\u00e9marche personnelle autour\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/nicotondeur.fr\/index.php\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/12\/20221124_122521_897.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/12\/20221124_122521_897.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/12\/20221124_122521_897.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/12\/20221124_122521_897.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/nicotondeur.fr\/wp-content\/uploads\/2022\/12\/20221124_122521_897.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1301"}],"version-history":[{"count":5,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1301\/revisions"}],"predecessor-version":[{"id":1314,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/posts\/1301\/revisions\/1314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/media\/1307"}],"wp:attachment":[{"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nicotondeur.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}